{"id":9569,"date":"2026-01-22T09:42:09","date_gmt":"2026-01-22T08:42:09","guid":{"rendered":"https:\/\/hi-nd.com\/?post_type=product&#038;p=9569"},"modified":"2026-01-23T14:36:35","modified_gmt":"2026-01-23T13:36:35","slug":"nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy","status":"publish","type":"product","link":"https:\/\/hi-nd.com\/es\/producto\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\/","title":{"rendered":"Q Carcasa de techo de una sola cara tramo de 37"},"content":{"rendered":"<table style=\"height: 100px;\" width=\"773\">\n<tbody>\n<tr>\n<td width=\"150\"><em> N\u00famero de pieza<\/em><\/td>\n<td width=\"300 \"><em> Descripci\u00f3n<\/em><\/td>\n<td width=\"330 \"><em> Pantallas compatibles<\/em><\/td>\n<td width=\"73\"><em> Color<\/em><\/td>\n<\/tr>\n<tr>\n<td> CC3712-0201-01<\/td>\n<td> Carcasa de techo unilateral extensible 37<\/td>\n<td> Samsung SH37C<\/td>\n<td> Blanco<\/td>\n<\/tr>\n<tr>\n<td> CC3712-0201-02<\/td>\n<td> Carcasa de techo unilateral extensible 37<\/td>\n<td> Samsung SH37C<\/td>\n<td> Negro<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>La Carcasa de Techo Estirada por un Solo Lado est\u00e1 dise\u00f1ada para pantallas de 37&#8243;. Es la soluci\u00f3n perfecta para soluciones de se\u00f1alizaci\u00f3n digital en tiendas. <\/p>\n<p>Color blanco y negro de serie<br \/>\nTodos los cables est\u00e1n ocultos<\/p>\n","protected":false},"featured_media":9590,"template":"","meta":[],"product_brand":[],"product_cat":[85,84],"product_tag":[],"class_list":{"0":"post-9569","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-carcasa","7":"product_cat-techo","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Q Carcasa de techo de una sola cara tramo de 37 - HI-ND<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hi-nd.com\/es\/producto\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Q Carcasa de techo de una sola cara tramo de 37 - HI-ND\" \/>\n<meta property=\"og:description\" content=\"La Carcasa de Techo Estirada por un Solo Lado est\u00e1 dise\u00f1ada para pantallas de 37&quot;. Es la soluci\u00f3n perfecta para soluciones de se\u00f1alizaci\u00f3n digital en tiendas.  Color blanco y negro de serie Todos los cables est\u00e1n ocultos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hi-nd.com\/es\/producto\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\/\" \/>\n<meta property=\"og:site_name\" content=\"HI-ND\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-23T13:36:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hi-nd.com\/wp-content\/uploads\/2026\/01\/CC3711-0101-01_01-750x750-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hi-nd.com\\\/es\\\/producto\\\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\\\/\",\"url\":\"https:\\\/\\\/hi-nd.com\\\/es\\\/producto\\\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\\\/\",\"name\":\"Q Carcasa de techo de una sola cara tramo de 37 - HI-ND\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hi-nd.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hi-nd.com\\\/es\\\/producto\\\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hi-nd.com\\\/es\\\/producto\\\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hi-nd.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/CC3711-0101-01_01-750x750-1.jpg\",\"datePublished\":\"2026-01-22T08:42:09+00:00\",\"dateModified\":\"2026-01-23T13:36:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hi-nd.com\\\/es\\\/producto\\\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hi-nd.com\\\/es\\\/producto\\\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hi-nd.com\\\/es\\\/producto\\\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hi-nd.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/CC3711-0101-01_01-750x750-1.jpg\",\"contentUrl\":\"https:\\\/\\\/hi-nd.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/CC3711-0101-01_01-750x750-1.jpg\",\"width\":750,\"height\":750,\"caption\":\"CC3712-0201-02\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hi-nd.com\\\/es\\\/producto\\\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hi-nd.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/hi-nd.com\\\/es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Q Carcasa de techo de una sola cara tramo de 37\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hi-nd.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/hi-nd.com\\\/es\\\/\",\"name\":\"HI-ND\",\"description\":\"Mounting Solutions\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hi-nd.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Q Carcasa de techo de una sola cara tramo de 37 - HI-ND","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hi-nd.com\/es\/producto\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\/","og_locale":"es_ES","og_type":"article","og_title":"Q Carcasa de techo de una sola cara tramo de 37 - HI-ND","og_description":"La Carcasa de Techo Estirada por un Solo Lado est\u00e1 dise\u00f1ada para pantallas de 37\". Es la soluci\u00f3n perfecta para soluciones de se\u00f1alizaci\u00f3n digital en tiendas.  Color blanco y negro de serie Todos los cables est\u00e1n ocultos","og_url":"https:\/\/hi-nd.com\/es\/producto\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\/","og_site_name":"HI-ND","article_modified_time":"2026-01-23T13:36:35+00:00","og_image":[{"width":750,"height":750,"url":"https:\/\/hi-nd.com\/wp-content\/uploads\/2026\/01\/CC3711-0101-01_01-750x750-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hi-nd.com\/es\/producto\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\/","url":"https:\/\/hi-nd.com\/es\/producto\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\/","name":"Q Carcasa de techo de una sola cara tramo de 37 - HI-ND","isPartOf":{"@id":"https:\/\/hi-nd.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hi-nd.com\/es\/producto\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\/#primaryimage"},"image":{"@id":"https:\/\/hi-nd.com\/es\/producto\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\/#primaryimage"},"thumbnailUrl":"https:\/\/hi-nd.com\/wp-content\/uploads\/2026\/01\/CC3711-0101-01_01-750x750-1.jpg","datePublished":"2026-01-22T08:42:09+00:00","dateModified":"2026-01-23T13:36:35+00:00","breadcrumb":{"@id":"https:\/\/hi-nd.com\/es\/producto\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hi-nd.com\/es\/producto\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hi-nd.com\/es\/producto\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\/#primaryimage","url":"https:\/\/hi-nd.com\/wp-content\/uploads\/2026\/01\/CC3711-0101-01_01-750x750-1.jpg","contentUrl":"https:\/\/hi-nd.com\/wp-content\/uploads\/2026\/01\/CC3711-0101-01_01-750x750-1.jpg","width":750,"height":750,"caption":"CC3712-0201-02"},{"@type":"BreadcrumbList","@id":"https:\/\/hi-nd.com\/es\/producto\/nueva-ventana-para-carcasa-de-techo-para-samsung-om55-copy-copy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hi-nd.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/hi-nd.com\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Q Carcasa de techo de una sola cara tramo de 37"}]},{"@type":"WebSite","@id":"https:\/\/hi-nd.com\/es\/#website","url":"https:\/\/hi-nd.com\/es\/","name":"HI-ND","description":"Mounting Solutions","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hi-nd.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/hi-nd.com\/es\/wp-json\/wp\/v2\/product\/9569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hi-nd.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hi-nd.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hi-nd.com\/es\/wp-json\/wp\/v2\/media\/9590"}],"wp:attachment":[{"href":"https:\/\/hi-nd.com\/es\/wp-json\/wp\/v2\/media?parent=9569"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hi-nd.com\/es\/wp-json\/wp\/v2\/product_brand?post=9569"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hi-nd.com\/es\/wp-json\/wp\/v2\/product_cat?post=9569"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hi-nd.com\/es\/wp-json\/wp\/v2\/product_tag?post=9569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}